{"id":7912,"date":"2026-07-15T03:11:00","date_gmt":"2026-07-15T00:11:00","guid":{"rendered":"https:\/\/www.schooler.org.ua\/uk-uavcheni-vilovljujut-bakteriyi-jaki-diljatsja-bilkami-schob\/"},"modified":"2026-07-15T03:11:00","modified_gmt":"2026-07-15T00:11:00","slug":"uk-uavcheni-vilovljujut-bakteriyi-jaki-diljatsja-bilkami-schob","status":"publish","type":"post","link":"https:\/\/www.schooler.org.ua\/es\/uk-uavcheni-vilovljujut-bakteriyi-jaki-diljatsja-bilkami-schob\/","title":{"rendered":"Las bacterias comparten prote\u00ednas para enga\u00f1ar a los antibi\u00f3ticos."},"content":{"rendered":"<p>El estr\u00e9s lo desencadena. <\/p>\n<p>Cuando los antibi\u00f3ticos atacan a un microbio, los vecinos entran en p\u00e1nico. Pero no de la manera que esper\u00e1bamos. No se limitan a refugiarse. Se acercan. Comparten prote\u00ednas. <\/p>\n<p>Suena salvaje, lo s\u00e9. Siempre hemos sabido que las bacterias comercian con ADN. La transferencia horizontal de genes es un elemento b\u00e1sico de la microbiolog\u00eda. Sabemos que transmiten genes de resistencia como si fueran obsequios de partido. Pero los cient\u00edficos sospechan desde hace mucho tiempo que existe una capa m\u00e1s oscura y compleja. Quiz\u00e1s tambi\u00e9n intercambien prote\u00ednas funcionales. Se pensaba que peque\u00f1as burbujas de l\u00edquido llamadas ves\u00edculas eran camiones de reparto. Membranas grasas, carga de prote\u00ednas, zip zip desaparecido. <\/p>\n<p>\u00bfPero la prueba? <\/p>\n<p>No estaba all\u00ed. <\/p>\n<p>\u201c[Si miras atr\u00e1s], no hab\u00eda pruebas\u201d, dice Christophe. Herman, microbi\u00f3logo de la Facultad de Medicina de Baylor. Hasta ahora. \u00c9l y su equipo acaban de publicar un art\u00edculo en <em>Science<\/em> que finalmente da cuenta de lo ocurrido. Vivir. En cinta, por as\u00ed decirlo. <\/p>\n<h3>La trampa<\/h3>\n<p>Herman y sus colegas le tendieron una trampa. Simple. Elegante. Utilizaron dos poblaciones de <em>E. coli<\/em>. <\/p>\n<p>Primero, los destinatarios. Estos pobres bastardos portaban un gen roto. Invertida, in\u00fatil, silenciosa. Sin una versi\u00f3n funcional de este gen espec\u00edfico, no podr\u00edan procesar la galactosa, un az\u00facar simple. B\u00e1sicamente, estaban hambrientos de esa fuente de energ\u00eda espec\u00edfica. <\/p>\n<p>Luego los donantes. Estos tipos ten\u00edan un arma: Cre recombinasa. Una prote\u00edna que puede reparar genes invertidos. Act\u00faa como un par de tijeras y cinta adhesiva. Corta y pega el gen para que vuelva a funcionar. Si una c\u00e9lula receptora recibiera esta prote\u00edna Cre, podr\u00eda volver a activar el gen. Modo fiesta habilitado. <\/p>\n<p>Aqu\u00ed est\u00e1 el truco. La transferencia de ADN no funcionar\u00eda aqu\u00ed. Los destinatarios necesitaban la prote\u00edna real para solucionar el problema inmediato. Tuvieron que recibir f\u00edsicamente la recombinasa Cre de un donante. <\/p>\n<p>El experimento parec\u00eda destinado al fracaso. O aburrimiento. <\/p>\n<blockquote>\n<p>&#8220;[Herman] se fue de vacaciones. Yo estaba en el laboratorio. No creo que esper\u00e1ramos nada&#8221;, recuerda la autora principal, Alice Wen. <\/p>\n<\/blockquote>\n<p>Observaron las placas de Petri. Pasaron los d\u00edas. Y luego. Lenta y laboriosamente, apareci\u00f3 la se\u00f1al. Las bacterias * s\u00ed * compartieron. La prote\u00edna Cre se movi\u00f3. Los destinatarios comieron la galactosa. El intercambio sucedi\u00f3. <\/p>\n<p>Aunque fue terriblemente lento. Un chorrito, no una inundaci\u00f3n. <\/p>\n<p>Hasta que la presi\u00f3n aument\u00f3. <\/p>\n<h3>El efecto antibi\u00f3tico<\/h3>\n<p>Eche antibi\u00f3ticos a la mezcla. <\/p>\n<p>Mira la reacci\u00f3n. <\/p>\n<p>La tasa de transferencia se dispar\u00f3. Por un factor de cuatro mil. Eso no es una fluctuaci\u00f3n. Esa es una respuesta de p\u00e1nico. El estr\u00e9s de la droga obliga a la comunidad a un fren\u00e9tico intercambio de recursos. <\/p>\n<p>En la naturaleza, esto divide a las bacterias en dos tribus. Los m\u00e1rtires y los durmientes. <\/p>\n<p>La mayor\u00eda de las c\u00e9lulas reaccionan desprendendo ves\u00edculas. Descargan cargas de prote\u00ednas al medio ambiente, dej\u00e1ndose expuestos. Es una especie de pacto suicida, pero la carga cae sobre los vecinos. Mientras tanto, otras c\u00e9lulas se quedan en silencio. Dejan de reproducirse. Cerraron la producci\u00f3n de prote\u00ednas para esconderse de la droga. Est\u00e1n inactivos, fr\u00e1giles y necesitan ayuda. <\/p>\n<p>Herman cree que las ves\u00edculas proporcionan herramientas de reparaci\u00f3n. ADN polimerasas. Cosas que estas c\u00e9lulas inactivas necesitan para reiniciar la vida una vez que cesa el bombardeo. Los vivos alimentan a los dormidos. Funciona incluso a trav\u00e9s de fronteras entre especies. <\/p>\n<p>\u00bfPor qu\u00e9? <\/p>\n<p>Qui\u00e9n sabe. Realmente no lo sabemos. <\/p>\n<blockquote>\n<p>\u201cSimplemente sabemos que sucede\u201d, dice Wen. <\/p>\n<\/blockquote>\n<p>Quiz\u00e1s sea la supervivencia de la poblaci\u00f3n. Una c\u00e9lula muere y las dem\u00e1s viven. O tal vez sea ego\u00edsta de una manera sutil. Quiz\u00e1s una c\u00e9lula tome la prote\u00edna de un vecino para probarla. Una prueba libre de microbios. Antes de comprometerse a robar bienes permanentes, como el ADN, primero prueba las habilidades del vecino. <\/p>\n<p>Funciona. Esa es la cuesti\u00f3n. <\/p>\n<p>Laurence Van Melderen de la Universidad Libre de Bruselas no particip\u00f3 en la investigaci\u00f3n. Ella mir\u00f3 desde afuera. A ella le gusta lo que ve. <\/p>\n<p>&#8220;Esta es una forma muy elegante de demostrar que existe la transferencia de prote\u00ednas. Estoy segura de que tienen raz\u00f3n&#8221;, afirma. <\/p>\n<p>Los controles eran estrictos. Sin lagunas. La conclusi\u00f3n se mantiene. Las bacterias comparten su hardware cuando las cosas se ponen mal. Pasan la antorcha. Comparten la carga. <\/p>\n<p>Generalmente pensamos en la supervivencia del m\u00e1s fuerte como un deporte solitario. El solitario. El m\u00e1s fuerte. Pero aqu\u00ed, a nivel microsc\u00f3pico, la comunidad importa m\u00e1s que el individuo. Construyen una red de seguridad hecha de grasas y prote\u00ednas. <\/p>\n<p>Nos deja pregunt\u00e1ndonos qui\u00e9n es el verdadero enemigo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El estr\u00e9s lo desencadena. Cuando los antibi\u00f3ticos atacan a un microbio, los vecinos entran en p\u00e1nico. Pero no de la manera que esper\u00e1bamos. No se limitan a refugiarse. Se acercan. Comparten prote\u00ednas. Suena salvaje, lo s\u00e9. Siempre hemos sabido que las bacterias comercian con ADN. La transferencia horizontal de genes es un elemento b\u00e1sico de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":""},"categories":[1],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/posts\/7912"}],"collection":[{"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/comments?post=7912"}],"version-history":[{"count":0,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/posts\/7912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/media\/7911"}],"wp:attachment":[{"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/media?parent=7912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/categories?post=7912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/tags?post=7912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}