{"id":7914,"date":"2026-07-15T04:24:09","date_gmt":"2026-07-15T01:24:09","guid":{"rendered":"https:\/\/www.schooler.org.ua\/uk-uavcheni-otrimali-najjaskravishu-kartinu-morskogo-dna-scho\/"},"modified":"2026-07-15T04:24:09","modified_gmt":"2026-07-15T01:24:09","slug":"uk-uavcheni-otrimali-najjaskravishu-kartinu-morskogo-dna-scho","status":"publish","type":"post","link":"https:\/\/www.schooler.org.ua\/es\/uk-uavcheni-otrimali-najjaskravishu-kartinu-morskogo-dna-scho\/","title":{"rendered":"La corteza terrestre se mueve en explosiones violentas"},"content":{"rendered":"<p>Debajo del oc\u00e9ano, el planeta respira. <\/p>\n<p>Es un proceso lento, mayoritariamente. Las placas tect\u00f3nicas se separan unas de otras a lo largo de esas enormes cadenas monta\u00f1osas submarinas. Las llamamos dorsales en medio del oc\u00e9ano. El magma burbujea para llenar los huecos. La lava se enfr\u00eda. Se forma nueva corteza. Es literalmente el juego de \u201cEl suelo es lava\u201d m\u00e1s grande del planeta. <\/p>\n<p>Sab\u00edamos c\u00f3mo funcionaba en abstracto. Millones de a\u00f1os de libros de geolog\u00eda cuentan la historia. Aunque realmente nunca vimos que sucediera. No precisamente. No con c\u00e1maras y sensores mirando directamente a la herida mientras se abre. <\/p>\n<p>Hasta ahora. <\/p>\n<p>En el Oc\u00e9ano \u00cdndico, los investigadores tuvieron suerte. Desplegaron todo un arsenal de tecnolog\u00eda. Transpondedores ac\u00fasticos. Man\u00f3metros. Balizas geod\u00e9sicas. <em>Hidr\u00f3fonos<\/em>, esos o\u00eddos submarinos para escuchar temblores s\u00edsmicos. Lo configuraron y esperaron. <\/p>\n<p>Dos meses es una eternidad en el tiempo humano. En geolog\u00eda, es un parpadeo. <\/p>\n<p>La tierra se movi\u00f3. <\/p>\n<p>Menos de seis semanas despu\u00e9s de la instalaci\u00f3n, un enjambre de terremotos destroz\u00f3 la cresta. El fondo marino no s\u00f3lo se desplaz\u00f3; cay\u00f3 cuatro metros. Doce pies. Las placas se rompieron en un metro entero. Y luego vino el incendio. Ciento sesenta millones de metros c\u00fabicos de lava inundaron el fondo marino. Esa es suficiente roca para construir sesenta Grandes Pir\u00e1mides de Giza. Sesenta. <\/p>\n<blockquote>\n<p>&#8220;Esper\u00e1bamos medir unos pocos mil\u00edmetros, tal vez.&#8221; <\/p>\n<\/blockquote>\n<p>Ese es Jean-Yves Royer del Laboratoire de Plan\u00e9tologie et de G\u00e9odynamique de Nantes. Fue el l\u00edder del estudio publicado en <em>Nature<\/em>. El equipo pens\u00f3 que ver\u00edan cent\u00edmetros. Vieron el movimiento de toda una vida en un fin de semana violento. Casi cuarenta a\u00f1os de deriva tect\u00f3nica sucedieron instant\u00e1neamente. <\/p>\n<p>Esto es importante porque desmiente el mito de &#8220;lento y constante&#8221;. Las placas no se deslizan como discos deslizantes. Se quedan. Se esfuerzan. Se rompen. <\/p>\n<p>Aqu\u00ed est\u00e1 el misterio m\u00e1s profundo que resolvieron. <\/p>\n<p>Los cient\u00edficos siempre se preguntaron c\u00f3mo se mov\u00edan estas fallas sin sacudir el suelo. Hay un &#8220;deslizamiento as\u00edsmico&#8221;. Es un t\u00e9rmino enga\u00f1oso. Significa que la roca se est\u00e1 moviendo, pasando junto a su vecina, pero no hay terremoto. Sin explosi\u00f3n. Sin sacudidas. Simplemente deslizamiento silencioso. <\/p>\n<p>\u00bfEse deslizamiento silencioso es provocado por magma? No lo sab\u00edamos. <\/p>\n<p>Los nuevos datos dicen que s\u00ed. <\/p>\n<p>La l\u00ednea de falla se desplaz\u00f3 unos dos metros. \u00bfLos terremotos? S\u00f3lo representan entre diez y veinte cent\u00edmetros. \u00bfEl resto de ese salto de dos metros? Sucedi\u00f3 en silencio. Despu\u00e9s de que las rocas se hubieran agrietado. <\/p>\n<p><em>No es s\u00f3lo que el desliz exista. Ocurre cuando llega el magma.<\/em> <\/p>\n<p>Hannah F. Mark, que no particip\u00f3 en el estudio pero lo observa de cerca desde la Universidad de Columbia, dio en el clavo. El deslizamiento est\u00e1 causalmente relacionado con la masa fundida. <\/p>\n<p>\u00bfPor qu\u00e9 esto cambia las cosas? <\/p>\n<p>Porque explica el silencio de las profundidades del mar. Las dorsales en medio del oc\u00e9ano deber\u00edan ser m\u00e1s ruidosas. Si sumas todos los movimientos de las placas, esperar\u00edas sacudidas constantes. En cambio, una parte se hunde silenciosamente en el abismo. Demasiado silencioso para darse cuenta. <\/p>\n<p>A menos que coloques un puesto de escucha en el fondo del mundo y esperes. <\/p>\n<p>Y luego tal vez, s\u00f3lo tal vez, tengas un espect\u00e1culo. \ud83c\udf0b<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debajo del oc\u00e9ano, el planeta respira. Es un proceso lento, mayoritariamente. Las placas tect\u00f3nicas se separan unas de otras a lo largo de esas enormes cadenas monta\u00f1osas submarinas. Las llamamos dorsales en medio del oc\u00e9ano. El magma burbujea para llenar los huecos. La lava se enfr\u00eda. Se forma nueva corteza. Es literalmente el juego de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":""},"categories":[1],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/posts\/7914"}],"collection":[{"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/comments?post=7914"}],"version-history":[{"count":0,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/posts\/7914\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/media\/7913"}],"wp:attachment":[{"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/media?parent=7914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/categories?post=7914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/tags?post=7914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}