{"id":7916,"date":"2026-07-15T04:33:10","date_gmt":"2026-07-15T01:33:10","guid":{"rendered":"https:\/\/www.schooler.org.ua\/uk-uakosmonavti-zrobili-pershi-rentgenivski-znimki-v-kosmosi-ru\/"},"modified":"2026-07-15T04:33:10","modified_gmt":"2026-07-15T01:33:10","slug":"uk-uakosmonavti-zrobili-pershi-rentgenivski-znimki-v-kosmosi-ru","status":"publish","type":"post","link":"https:\/\/www.schooler.org.ua\/es\/uk-uakosmonavti-zrobili-pershi-rentgenivski-znimki-v-kosmosi-ru\/","title":{"rendered":"Space Meds acaba de recibir una actualizaci\u00f3n: los rayos X llegan a la \u00f3rbita"},"content":{"rendered":"<blockquote>\n<p>&#8220;La adquisici\u00f3n de radiograf\u00edas \u00fatiles para el diagn\u00f3stico es algo que cualquiera puede hacer.&#8221; \u2014Sheyna Gifford <\/p>\n<\/blockquote>\n<p>Durante d\u00e9cadas, resistimos con los ultrasonidos. Cuarenta a\u00f1os. Durante ese tiempo, el ultrasonido rein\u00f3 en la medicina espacial. No fue una elecci\u00f3n de dise\u00f1o. Fue justo lo que funcion\u00f3. Y apenas. <\/p>\n<p>Operarlo requiri\u00f3 una extensa capacitaci\u00f3n. Las ondas sonoras odian las caba\u00f1as ruidosas y estrechas. \u00bfManteniendo una se\u00f1al clara all\u00ed arriba? <em>Pesadilla.<\/em> <\/p>\n<p>Entonces, \u00bfpor qu\u00e9 no llevamos una m\u00e1quina de rayos X? <\/p>\n<p>Masa. Calor. Radiaci\u00f3n. Quietud. Todo flota. Todo vibra. Obtener una imagen de diagn\u00f3stico n\u00edtida mientras orbitaba a 17.500 millas por hora parec\u00eda t\u00e9cnicamente imposible. Una presunci\u00f3n, de verdad. Un l\u00edmite estricto. <\/p>\n<p>Sheyna Gifford, de la Cl\u00ednica Mayo, dice que siempre ha sido el sue\u00f1o de la medicina aeroespacial. Una modalidad. S\u00f3lo uno. \u00bfQu\u00e9 tan fr\u00e1gil es eso? <\/p>\n<p>Ingrese el MinXray TR90B. Es peque\u00f1o. Aproximadamente del tama\u00f1o de una hielera. Grado comercial. Cosas disponibles en el mercado. Gifford y su equipo no esperaron a que las condiciones fueran perfectas. En 2022 lo probaron en vuelos parab\u00f3licos, simulando la microgravedad. Los escaneos se mantuvieron. <\/p>\n<p>Pero las pruebas sobre el terreno son mentiras reconfortantes. El espacio es el verdadero examen. <\/p>\n<h3>El experimento Fram2<\/h3>\n<p>Se asociaron con SpaceX. Ni otro salto de avi\u00f3n. \u00d3rbita <em>real<\/em>. La misi\u00f3n era Fram2. El a\u00f1o pasado. En marzo de 2025 se produjo el lanzamiento. <\/p>\n<p>Aqu\u00ed est\u00e1 el truco: no habr\u00e1 meses de preparaci\u00f3n para la escuela de medicina para los astronautas. <\/p>\n<p>Cuatro horas. <\/p>\n<p>Ese fue el tiempo total de entrenamiento de la tripulaci\u00f3n en este aparato de radiograf\u00eda port\u00e1til. Corto, \u00bfverdad? Luego se lanzaron. Los esc\u00e1neres previos al vuelo cubrieron las manos, los antebrazos, el pecho, el abdomen y la pelvis. L\u00edneas de base en la Tierra. <\/p>\n<p>En el espacio, la rutina se repiti\u00f3. Calibraci\u00f3n. Escanear. Mano. Antebrazo. Pecho. Abdomen. Pelvis. <\/p>\n<p>Esperar. \u00bfPor qu\u00e9 escanear un reloj? <\/p>\n<p>Tambi\u00e9n le hicieron una radiograf\u00eda a un reloj inteligente. Solo para demostrar que el sistema funciona tanto en hardware como en tejido humano. La electr\u00f3nica importa. Los trajes espaciales importan. No se puede desmontar un traje espacial para comprobar el desgaste interno. Necesitas ver el interior sin derribarlo. <\/p>\n<h3>\u00bfFuncion\u00f3?<\/h3>\n<p>Tres radi\u00f3logos independientes volvieron a poner sus ojos en los datos orbitales en tierra. <\/p>\n<p>\u00bfPosicionamiento para los golpes centrales al cuerpo? Ligeramente apagado. Flotar hace que &#8220;quedarse quieto&#8221; sea un desaf\u00edo. <\/p>\n<p>\u00bfPero todo lo dem\u00e1s? Afilado. La resoluci\u00f3n y el contraste coincidieron con los escaneos est\u00e1ndar de la Tierra. <\/p>\n<blockquote>\n<p>&#8220;Tres personas no m\u00e9dicas muy talentosas con cuatro horas de formaci\u00f3n&#8230; lo hicieron bien&#8221;. <\/p>\n<\/blockquote>\n<p>Gifford no permite que nadie le reste importancia. En uno de los entornos m\u00e1s duros e implacables que existen, los miembros de la tripulaci\u00f3n no m\u00e9dicos utilizaron equipo m\u00e9dico. Lo lograron. <\/p>\n<p>Hay contratiempos. La m\u00e1quina sufri\u00f3 algunos da\u00f1os est\u00e9ticos durante el viaje en cohete. Las fuerzas hacia arriba y hacia abajo son brutales en el hardware de consumo. Eso necesita arreglo. <\/p>\n<p>\u00bfEl futuro? M\u00e1quinas m\u00e1s peque\u00f1as. M\u00e1s exploraciones de rutina. No s\u00f3lo para huesos rotos. Para comprobar los trajes de soporte vital que te mantienen con vida. <\/p>\n<p>Todav\u00eda no estamos en la Luna con cabinas de rayos X. Pero ya no estamos ciegos en \u00f3rbita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;La adquisici\u00f3n de radiograf\u00edas \u00fatiles para el diagn\u00f3stico es algo que cualquiera puede hacer.&#8221; \u2014Sheyna Gifford Durante d\u00e9cadas, resistimos con los ultrasonidos. Cuarenta a\u00f1os. Durante ese tiempo, el ultrasonido rein\u00f3 en la medicina espacial. No fue una elecci\u00f3n de dise\u00f1o. Fue justo lo que funcion\u00f3. Y apenas. Operarlo requiri\u00f3 una extensa capacitaci\u00f3n. Las ondas sonoras [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7915,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":""},"categories":[1],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/posts\/7916"}],"collection":[{"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/comments?post=7916"}],"version-history":[{"count":0,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/posts\/7916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/media\/7915"}],"wp:attachment":[{"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/media?parent=7916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/categories?post=7916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schooler.org.ua\/es\/wp-json\/wp\/v2\/tags?post=7916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}