{"id":7912,"date":"2026-07-15T03:11:00","date_gmt":"2026-07-15T00:11:00","guid":{"rendered":"https:\/\/www.schooler.org.ua\/uk-uavcheni-vilovljujut-bakteriyi-jaki-diljatsja-bilkami-schob\/"},"modified":"2026-07-15T03:11:00","modified_gmt":"2026-07-15T00:11:00","slug":"uk-uavcheni-vilovljujut-bakteriyi-jaki-diljatsja-bilkami-schob","status":"publish","type":"post","link":"https:\/\/www.schooler.org.ua\/fr\/uk-uavcheni-vilovljujut-bakteriyi-jaki-diljatsja-bilkami-schob\/","title":{"rendered":"Les bact\u00e9ries partagent des prot\u00e9ines pour tromper les antibiotiques"},"content":{"rendered":"<p>Le stress le d\u00e9clenche. <\/p>\n<p>Lorsque les antibiotiques frappent un microbe, les voisins paniquent. Mais pas comme nous l\u2019esp\u00e9rions. Ils ne se contentent pas de se cacher. Ils tendent la main. Ils partagent des prot\u00e9ines. <\/p>\n<p>Cela semble fou, je sais. Nous savons depuis toujours que les bact\u00e9ries \u00e9changent de l\u2019ADN. Le transfert horizontal de g\u00e8nes est un \u00e9l\u00e9ment essentiel de la microbiologie. Nous savons qu\u2019ils transmettent des g\u00e8nes de r\u00e9sistance comme des cadeaux de f\u00eate. Mais les scientifiques soup\u00e7onnent depuis longtemps l\u2019existence d\u2019une couche plus sombre et plus complexe. Peut-\u00eatre qu\u2019ils \u00e9changent aussi des prot\u00e9ines fonctionnelles. On pensait que de minuscules bulles de liquide appel\u00e9es v\u00e9sicules \u00e9taient les camions de livraison. Membranes grasses, cargaison de prot\u00e9ines, zip zip disparu. <\/p>\n<p>Mais la preuve ? <\/p>\n<p>Ce n&#8217;\u00e9tait pas l\u00e0. <\/p>\n<p>\u00ab [Si vous regardez en arri\u00e8re], il n\u2019y avait aucune preuve \u00bb, pr\u00e9cise Christophe. Herman, microbiologiste au Baylor College of Medicine. Jusqu&#8217;\u00e0 maintenant. Lui et son \u00e9quipe viennent de publier un article dans <em>Science<\/em> qui r\u00e9v\u00e8le enfin l&#8217;affaire. En direct. Sur bande, pour ainsi dire. <\/p>\n<h3>Le pi\u00e8ge<\/h3>\n<p>Herman et ses coll\u00e8gues ont tendu un pi\u00e8ge. Simple. \u00c9l\u00e9gant. Ils ont utilis\u00e9 deux populations de <em>E. coli<\/em>. <\/p>\n<p>Tout d\u2019abord, les destinataires. Ces pauvres salauds portaient un g\u00e8ne cass\u00e9. Invers\u00e9, inutile, silencieux. Sans une version fonctionnelle de ce g\u00e8ne sp\u00e9cifique, ils ne pourraient pas traiter le galactose, un simple sucre. Ils \u00e9taient essentiellement affam\u00e9s de cette source d\u2019\u00e9nergie sp\u00e9cifique. <\/p>\n<p>Puis les donateurs. Ces types avaient une arme : la Cre recombinase. Une prot\u00e9ine qui peut r\u00e9parer les g\u00e8nes invers\u00e9s. Cela agit comme une paire de ciseaux et du ruban adh\u00e9sif. Il coupe et colle le g\u00e8ne pour le remettre en \u00e9tat de marche. Si une cellule receveuse recevait cette prot\u00e9ine Cre, elle pourrait r\u00e9activer le g\u00e8ne. Mode F\u00eate activ\u00e9. <\/p>\n<p>Voici le pi\u00e8ge. Le transfert d\u2019ADN ne ferait pas l\u2019affaire ici. Les destinataires avaient besoin de la prot\u00e9ine r\u00e9elle pour r\u00e9soudre le probl\u00e8me imm\u00e9diat. Ils devaient recevoir physiquement la recombinase Cre d\u2019un donneur. <\/p>\n<p>L\u2019exp\u00e9rience semblait vou\u00e9e \u00e0 l\u2019\u00e9chec. Ou l&#8217;ennui. <\/p>\n<blockquote>\n<p>&#8220;[Herman] est parti en vacances. J&#8217;\u00e9tais au laboratoire. Je ne pense pas que nous nous attendions \u00e0 quoi que ce soit&#8221;, se souvient l&#8217;auteur principal Alice Wen. <\/p>\n<\/blockquote>\n<p>Ils regard\u00e8rent les bo\u00eetes de P\u00e9tri. Les jours pass\u00e8rent. Et puis. Lentement, p\u00e9niblement, le signal est apparu. Les bact\u00e9ries <em>ont<\/em> partag\u00e9. La prot\u00e9ine Cre s&#8217;est d\u00e9plac\u00e9e. Les receveurs ont mang\u00e9 le galactose. Le commerce a eu lieu. <\/p>\n<p>Mais c&#8217;\u00e9tait terriblement lent. Un filet, pas une inondation. <\/p>\n<p>Jusqu\u2019\u00e0 ce que la pression monte. <\/p>\n<h3>L&#8217;effet antibiotique<\/h3>\n<p>Jetez des antibiotiques sur le m\u00e9lange. <\/p>\n<p>Regardez la r\u00e9action. <\/p>\n<p>Le taux de transfert est mont\u00e9 en fl\u00e8che. D&#8217;un facteur quatre mille. Ce n\u2019est pas une fluctuation. C&#8217;est une r\u00e9action de panique. Le stress de la drogue force la communaut\u00e9 \u00e0 un \u00e9change fr\u00e9n\u00e9tique de ressources. <\/p>\n<p>Dans la nature, cela divise les bact\u00e9ries en deux tribus. Les martyrs et les endormis. <\/p>\n<p>La plupart des cellules r\u00e9agissent en excr\u00e9tant des v\u00e9sicules. Ils d\u00e9chargent des cargaisons de prot\u00e9ines dans l\u2019environnement, se laissant ainsi expos\u00e9s. C\u2019est une sorte de pacte de suicide, mais la cargaison atterrit sur les voisins. Pendant ce temps, les autres cellules restent silencieuses. Ils arr\u00eatent de se reproduire. Ils ont arr\u00eat\u00e9 la production de prot\u00e9ines pour se cacher de la drogue. Ils sont endormis, fragiles et ont besoin d\u2019aide. <\/p>\n<p>Herman pense que les v\u00e9sicules fournissent des outils de r\u00e9paration. ADN polym\u00e9rases. Remplissez ces cellules dormantes dont elles ont besoin pour reprendre vie une fois le bombardement termin\u00e9. Les vivants nourrissent les dormeurs. Cela fonctionne m\u00eame au-del\u00e0 des fronti\u00e8res entre les esp\u00e8ces. <\/p>\n<p>Pourquoi? <\/p>\n<p>Qui sait. Nous ne savons vraiment pas. <\/p>\n<blockquote>\n<p>\u00ab Nous savons simplement que cela arrive \u00bb, d\u00e9clare Wen. <\/p>\n<\/blockquote>\n<p>C\u2019est peut-\u00eatre la survie de la population. Une cellule meurt donc les autres vivent. Ou peut-\u00eatre que c\u2019est \u00e9go\u00efste d\u2019une mani\u00e8re subtile. Peut-\u00eatre qu&#8217;une cellule saisit la prot\u00e9ine d&#8217;un voisin pour la tester. Un essai sans microbes. Avant de s\u2019engager \u00e0 voler des biens permanents, comme l\u2019ADN, il teste d\u2019abord les comp\u00e9tences du voisin. <\/p>\n<p>\u00c7a marche. C\u2019est \u00e7a le probl\u00e8me. <\/p>\n<p>Laurence Van Melderen de l&#8217;Universit\u00e9 Libre de Bruxelles n&#8217;a pas particip\u00e9 \u00e0 la recherche. Elle regardait de l&#8217;ext\u00e9rieur. Elle aime ce qu&#8217;elle voit. <\/p>\n<p>&#8220;C&#8217;est une fa\u00e7on tr\u00e8s \u00e9l\u00e9gante de prouver l&#8217;existence du transfert de prot\u00e9ines. Je suis convaincue qu&#8217;ils ont raison&#8221;, dit-elle. <\/p>\n<p>Les contr\u00f4les \u00e9taient stricts. Aucune faille. La conclusion tient. Les bact\u00e9ries partagent leur mat\u00e9riel lorsque les choses tournent mal. Ils passent le flambeau. Ils partagent la charge. <\/p>\n<p>Nous consid\u00e9rons g\u00e9n\u00e9ralement la survie du plus fort comme un sport solitaire. Le solitaire. Le plus fort. Mais ici, au niveau microscopique, la communaut\u00e9 compte plus que l\u2019individu. Ils construisent un filet de s\u00e9curit\u00e9 compos\u00e9 de graisses et de prot\u00e9ines. <\/p>\n<p>On se demande alors qui est le v\u00e9ritable ennemi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le stress le d\u00e9clenche. Lorsque les antibiotiques frappent un microbe, les voisins paniquent. Mais pas comme nous l\u2019esp\u00e9rions. Ils ne se contentent pas de se cacher. Ils tendent la main. Ils partagent des prot\u00e9ines. Cela semble fou, je sais. Nous savons depuis toujours que les bact\u00e9ries \u00e9changent de l\u2019ADN. Le transfert horizontal de g\u00e8nes est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":""},"categories":[1],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.schooler.org.ua\/fr\/wp-json\/wp\/v2\/posts\/7912"}],"collection":[{"href":"https:\/\/www.schooler.org.ua\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schooler.org.ua\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/fr\/wp-json\/wp\/v2\/comments?post=7912"}],"version-history":[{"count":0,"href":"https:\/\/www.schooler.org.ua\/fr\/wp-json\/wp\/v2\/posts\/7912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/fr\/wp-json\/wp\/v2\/media\/7911"}],"wp:attachment":[{"href":"https:\/\/www.schooler.org.ua\/fr\/wp-json\/wp\/v2\/media?parent=7912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schooler.org.ua\/fr\/wp-json\/wp\/v2\/categories?post=7912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schooler.org.ua\/fr\/wp-json\/wp\/v2\/tags?post=7912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}