{"id":7912,"date":"2026-07-15T03:11:00","date_gmt":"2026-07-15T00:11:00","guid":{"rendered":"https:\/\/www.schooler.org.ua\/uk-uavcheni-vilovljujut-bakteriyi-jaki-diljatsja-bilkami-schob\/"},"modified":"2026-07-15T03:11:00","modified_gmt":"2026-07-15T00:11:00","slug":"uk-uavcheni-vilovljujut-bakteriyi-jaki-diljatsja-bilkami-schob","status":"publish","type":"post","link":"https:\/\/www.schooler.org.ua\/pt\/uk-uavcheni-vilovljujut-bakteriyi-jaki-diljatsja-bilkami-schob\/","title":{"rendered":"As bact\u00e9rias compartilham prote\u00ednas para enganar os antibi\u00f3ticos"},"content":{"rendered":"<p>O estresse desencadeia isso. <\/p>\n<p>Quando os antibi\u00f3ticos atingem um micr\u00f3bio, os vizinhos entram em p\u00e2nico. Mas n\u00e3o da maneira que esper\u00e1vamos. Eles n\u00e3o apenas se acomodam. Eles estendem a m\u00e3o. Eles compartilham prote\u00ednas. <\/p>\n<p>Parece selvagem, eu sei. Sempre soubemos que bact\u00e9rias comercializam DNA. A transfer\u00eancia horizontal de genes \u00e9 um elemento b\u00e1sico da microbiologia. Sabemos que eles transmitem genes de resist\u00eancia como lembrancinhas. Mas os cientistas h\u00e1 muito suspeitam de uma camada mais escura e complexa. Talvez eles tamb\u00e9m comercializem prote\u00ednas funcionais. Acreditava-se que min\u00fasculas bolhas fluidas chamadas ves\u00edculas fossem os caminh\u00f5es de entrega. Membranas gordurosas, carga de prote\u00edna, zip zip desaparecido. <\/p>\n<p>Mas a prova? <\/p>\n<p>N\u00e3o estava l\u00e1. <\/p>\n<p>\u201c[Se voc\u00ea olhar para tr\u00e1s], n\u00e3o havia nenhuma evid\u00eancia\u201d, diz Christophe. Herman, microbiologista do Baylor College of Medicine. At\u00e9 agora. Ele e sua equipe acabaram de publicar um artigo na <em>Science<\/em> que finalmente mostra o que est\u00e1 acontecendo. Ao vivo. Em fita, por assim dizer. <\/p>\n<h3>A armadilha<\/h3>\n<p>Herman e seus colegas armaram uma armadilha. Simples. Elegante. Eles usaram duas popula\u00e7\u00f5es de <em>E. coli<\/em>. <\/p>\n<p>Primeiro, os destinat\u00e1rios. Esses pobres coitados carregavam um gene quebrado. Invertido, in\u00fatil, silencioso. Sem uma vers\u00e3o funcional deste gene espec\u00edfico, eles n\u00e3o poderiam processar a galactose, um a\u00e7\u00facar simples. Eles estavam essencialmente famintos por essa fonte de energia espec\u00edfica. <\/p>\n<p>Depois os doadores. Esses caras tinham uma arma: Cre recombinase. Uma prote\u00edna que pode consertar genes invertidos. Funciona como uma tesoura e fita adesiva. Ele corta e cola o gene de volta ao funcionamento. Se uma c\u00e9lula receptora recebesse esta prote\u00edna Cre, ela poderia reativar o gene. Modo festa ativado. <\/p>\n<p>Aqui est\u00e1 o problema. A transfer\u00eancia de DNA n\u00e3o funcionaria aqui. Os destinat\u00e1rios precisavam da prote\u00edna real para resolver o problema imediato. Eles tiveram que receber fisicamente a recombinase Cre de um doador. <\/p>\n<p>O experimento parecia destinado ao fracasso. Ou t\u00e9dio. <\/p>\n<blockquote>\n<p>&#8220;[Herman] saiu de f\u00e9rias. Eu estava no laborat\u00f3rio. Acho que n\u00e3o esper\u00e1vamos nada&#8221;, lembra a autora principal, Alice Wen. <\/p>\n<\/blockquote>\n<p>Eles observaram as placas de Petri. Os dias se passaram. E ent\u00e3o. Lentamente, meticulosamente, o sinal apareceu. As bact\u00e9rias <em>compartilharam<\/em>. A prote\u00edna Cre mudou. Os destinat\u00e1rios comeram a galactose. O com\u00e9rcio aconteceu. <\/p>\n<p>Mas foi dolorosamente lento. Um gotejamento, n\u00e3o uma inunda\u00e7\u00e3o. <\/p>\n<p>At\u00e9 a press\u00e3o aumentar. <\/p>\n<h3>O efeito antibi\u00f3tico<\/h3>\n<p>Jogue antibi\u00f3ticos na mistura. <\/p>\n<p>Observe a rea\u00e7\u00e3o. <\/p>\n<p>A taxa de transfer\u00eancia disparou. Por um fator de quatro mil. Isso n\u00e3o \u00e9 uma flutua\u00e7\u00e3o. Essa \u00e9 uma resposta de p\u00e2nico. O estresse da droga for\u00e7a a comunidade a uma troca fren\u00e9tica de recursos. <\/p>\n<p>Na natureza, isso divide as bact\u00e9rias em duas tribos. Os m\u00e1rtires e os adormecidos. <\/p>\n<p>A maioria das c\u00e9lulas reage liberando ves\u00edculas. Eles descarregam cargas proteicas no meio ambiente, ficando expostos. \u00c9 uma esp\u00e9cie de pacto suicida, mas a carga cai sobre os vizinhos. Enquanto isso, outras c\u00e9lulas ficam em sil\u00eancio. Eles param de se reproduzir. Eles interromperam a produ\u00e7\u00e3o de prote\u00ednas para se esconderem da droga. Eles est\u00e3o adormecidos, fr\u00e1geis e precisam de ajuda. <\/p>\n<p>Herman acha que as ves\u00edculas fornecem ferramentas de reparo. DNA polimerases. Coisas que essas c\u00e9lulas adormecidas precisam para reiniciar a vida assim que o bombardeio parar. Os vivos alimentam os adormecidos. Funciona mesmo al\u00e9m dos limites das esp\u00e9cies. <\/p>\n<p>Por que? <\/p>\n<p>Quem sabe. N\u00f3s realmente n\u00e3o sabemos. <\/p>\n<blockquote>\n<p>\u201cN\u00f3s simplesmente sabemos que isso acontece\u201d, diz Wen. <\/p>\n<\/blockquote>\n<p>Talvez seja a sobreviv\u00eancia da popula\u00e7\u00e3o. Uma c\u00e9lula morre para que as outras vivam. Ou talvez seja ego\u00edsta de uma forma sutil. Talvez uma c\u00e9lula pegue a prote\u00edna de um vizinho para test\u00e1-la. Um teste gratuito microbiano. Antes de se comprometer a roubar bens permanentes, como o ADN, testa primeiro as capacidades do vizinho. <\/p>\n<p>Funciona. Essa \u00e9 a quest\u00e3o. <\/p>\n<p>Laurence Van Melderen, da Universit\u00e9 Libre de Bruxelles, n\u00e3o esteve envolvido na pesquisa. Ela assistiu do lado de fora. Ela gosta do que v\u00ea. <\/p>\n<p>&#8220;Esta \u00e9 uma forma muito elegante de provar a exist\u00eancia de transfer\u00eancia de prote\u00ednas. Tenho certeza de que eles est\u00e3o certos&#8221;, diz ela. <\/p>\n<p>Os controles eram rigorosos. Sem lacunas. A conclus\u00e3o \u00e9 v\u00e1lida. As bact\u00e9rias compartilham seu hardware quando as coisas ficam ruins. Eles passam a tocha. Eles compartilham a carga. <\/p>\n<p>Geralmente pensamos na sobreviv\u00eancia do mais apto como um esporte solit\u00e1rio. O solit\u00e1rio. O mais forte. Mas aqui, ao n\u00edvel microsc\u00f3pico, a comunidade \u00e9 mais importante do que o indiv\u00edduo. Eles constroem uma rede de seguran\u00e7a feita de gordura e prote\u00edna. <\/p>\n<p>Isso nos deixa imaginando quem \u00e9 o verdadeiro inimigo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O estresse desencadeia isso. Quando os antibi\u00f3ticos atingem um micr\u00f3bio, os vizinhos entram em p\u00e2nico. Mas n\u00e3o da maneira que esper\u00e1vamos. Eles n\u00e3o apenas se acomodam. Eles estendem a m\u00e3o. Eles compartilham prote\u00ednas. Parece selvagem, eu sei. Sempre soubemos que bact\u00e9rias comercializam DNA. A transfer\u00eancia horizontal de genes \u00e9 um elemento b\u00e1sico da microbiologia. Sabemos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":""},"categories":[1],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.schooler.org.ua\/pt\/wp-json\/wp\/v2\/posts\/7912"}],"collection":[{"href":"https:\/\/www.schooler.org.ua\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schooler.org.ua\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/pt\/wp-json\/wp\/v2\/comments?post=7912"}],"version-history":[{"count":0,"href":"https:\/\/www.schooler.org.ua\/pt\/wp-json\/wp\/v2\/posts\/7912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schooler.org.ua\/pt\/wp-json\/wp\/v2\/media\/7911"}],"wp:attachment":[{"href":"https:\/\/www.schooler.org.ua\/pt\/wp-json\/wp\/v2\/media?parent=7912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schooler.org.ua\/pt\/wp-json\/wp\/v2\/categories?post=7912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schooler.org.ua\/pt\/wp-json\/wp\/v2\/tags?post=7912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}